{"id":3850,"date":"2024-10-26T17:53:10","date_gmt":"2024-10-26T15:53:10","guid":{"rendered":"https:\/\/rugby-thanhnoa.ovh\/?page_id=3850"},"modified":"2024-10-26T18:07:47","modified_gmt":"2024-10-26T16:07:47","slug":"cac-saint-affrique-26-10-2024","status":"publish","type":"page","link":"https:\/\/rugby-thanhnoa.ovh\/index.php\/cac-saint-affrique-26-10-2024\/","title":{"rendered":"CAC &#8211; Saint-Affrique 26\/10\/2024"},"content":{"rendered":"\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 1254px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #323A45;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/index.php\/wp-json\/wp\/v2\/pages\/3850\"         data-lightbox-url=\"https:\/\/rugby-thanhnoa.ovh\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=106&#038;tag=0&#038;theme_id=1&#038;shortcode_id=210&#038;sort_by=filename&#038;order_by=asc&#038;current_url=%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fpages%2F3850\"         data-gallery-id=\"106\"         data-popup-width=\"900\"         data-popup-height=\"600\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"210\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"106\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/rugby-thanhnoa.ovh\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">            \t\t\t\t\t\t\t\t<div class=\"search_line bwg_tag_select_view\">\t\t\t\t\t\t\t\t       <div class=\"bwg_order_cont\">        <select id=\"bwg_order_0\" class=\"bwg_order bwg_order_0\" onchange=\"bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', 0, '', 'album', 1, '', this.value)\">          <option  value=\"default\">Order by Default<\/option>          <option  value=\"alt\">Title<\/option>          <option  value=\"date\">Date<\/option>          <option selected value=\"filename\">Filename<\/option>          <option  value=\"size\">Size<\/option>          <option  value=\"random\">Random<\/option>        <\/select>      <\/div>      \t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t    <div data-max-count=\"5\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"106\"         data-lightbox-url=\"https:\/\/rugby-thanhnoa.ovh\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=106&amp;tag=0&amp;theme_id=1&amp;shortcode_id=210&amp;sort_by=filename&amp;order_by=asc&amp;current_url=%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fpages%2F3850\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47999\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0001_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47999\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0001_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0001_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0001 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0001 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"48001\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0002_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"48001\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0002_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0002_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0002 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0002 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"48000\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0003_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"48000\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0003_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0003_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0003 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0003 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"48002\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0004_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"48002\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0004_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0004_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0004 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0004 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"48003\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0005_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"48003\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0005_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0005_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0005 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0005 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47995\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0006_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47995\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0006_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0006_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0006 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0006 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47994\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0007_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47994\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0007_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0007_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0007 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0007 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47997\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0008_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47997\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0008_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0008_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0008 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0008 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47993\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0009_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47993\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0009_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0009_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0009 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0009 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47996\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0010_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47996\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0010_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0010_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0010 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0010 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47998\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0011_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47998\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0011_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0011_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0011 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0011 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47991\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0012_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47991\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0012_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0012_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0012 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0012 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47989\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0013_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47989\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0013_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0013_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0013 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0013 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47990\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0014_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47990\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0014_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0014_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0014 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0014 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47992\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0015_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47992\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0015_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0015_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0015 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0015 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47987\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0016_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47987\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0016_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0016_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0016 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0016 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47986\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0017_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47986\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0017_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0017_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0017 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0017 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47984\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0018_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47984\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0018_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0018_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0018 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0018 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47985\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0019_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47985\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0019_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0019_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0019 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0019 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47982\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0020_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47982\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0020_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0020_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0020 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0020 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47983\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0021_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47983\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0021_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0021_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0021 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0021 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47988\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0022_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47988\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0022_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0022_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0022 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0022 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47981\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0023_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47981\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0023_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0023_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0023 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0023 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47978\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0024_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47978\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0024_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0024_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0024 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0024 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47977\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0025_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47977\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0025_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0025_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0025 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0025 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47979\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0026_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47979\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0026_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0026_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0026 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0026 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47980\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0027_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47980\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0027_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0027_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0027 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0027 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47974\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0028_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47974\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0028_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0028_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0028 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0028 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47972\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0029_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47972\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0029_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0029_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0029 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0029 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"47975\" href=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/DSC_0030_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"47975\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0030_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   src=\"https:\/\/rugby-thanhnoa.ovh\/wp-content\/uploads\/photo-gallery\/thumb\/DSC_0030_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1)_(1).jpg?bwg=1729958805\"                   alt=\"DSC 0030 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\"                   title=\"DSC 0030 (1) (1) (1) (1) (1) (1) (1) (1) (1) (1)\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\t\t\t\t\tbackground-color: rgba(255, 255, 255, 1.00);\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                      <span class=\"pagination-links_0 pagination-links\" data-pages-count=\"24\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Go to the first page\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Go to the previous page\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_0\" onkeypress=\"return bwg_change_page_0(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tof\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_0\">\t\t\t\t\t\t\t\t\t\t\t24\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-0\" title=\"Go to the next page\" href=\"\/index.php\/wp-json\/wp\/v2\/pages\/3850?page_number_0=2\">\u203a<\/a>                <a class=\"bwg-a last-page-0\" title=\"Go to the last page\" href=\"\/index.php\/wp-json\/wp\/v2\/pages\/3850?page_number_0=24\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 24;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1724003191\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/rugby-thanhnoa.ovh\/index.php\/wp-json\/wp\/v2\/pages\/3850"}],"collection":[{"href":"https:\/\/rugby-thanhnoa.ovh\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rugby-thanhnoa.ovh\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rugby-thanhnoa.ovh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rugby-thanhnoa.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=3850"}],"version-history":[{"count":2,"href":"https:\/\/rugby-thanhnoa.ovh\/index.php\/wp-json\/wp\/v2\/pages\/3850\/revisions"}],"predecessor-version":[{"id":3854,"href":"https:\/\/rugby-thanhnoa.ovh\/index.php\/wp-json\/wp\/v2\/pages\/3850\/revisions\/3854"}],"wp:attachment":[{"href":"https:\/\/rugby-thanhnoa.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=3850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}